{"id":38576,"date":"2023-05-24T09:39:45","date_gmt":"2023-05-24T06:39:45","guid":{"rendered":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente.jpg"},"modified":"2023-05-24T09:39:45","modified_gmt":"2023-05-24T06:39:45","slug":"program-nou-evenimente","status":"inherit","type":"attachment","link":"https:\/\/editura-unibuc.ro\/en\/program-nou-evenimente\/","title":{"rendered":"program nou evenimente"},"author":2010,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-38576","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente.jpg' rel=\"lightbox[38576]\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"283\" src=\"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-400x283.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2327,"height":1646,"file":"2023\/05\/program-nou-evenimente.jpg","filesize":1181262,"sizes":{"medium":{"file":"program-nou-evenimente-400x283.jpg","width":400,"height":283,"filesize":28955,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-400x283.jpg"},"large":{"file":"program-nou-evenimente-800x566.jpg","width":800,"height":566,"filesize":96936,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-800x566.jpg"},"thumbnail":{"file":"program-nou-evenimente-150x106.jpg","width":150,"height":106,"filesize":5524,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-150x106.jpg"},"medium_large":{"file":"program-nou-evenimente-768x543.jpg","width":768,"height":543,"filesize":86966,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-768x543.jpg"},"1536x1536":{"file":"program-nou-evenimente-1536x1086.jpg","width":1536,"height":1086,"filesize":266958,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-1536x1086.jpg"},"2048x2048":{"file":"program-nou-evenimente-2048x1449.jpg","width":2048,"height":1449,"filesize":421153,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-2048x1449.jpg"},"post-thumbnail":{"file":"program-nou-evenimente-800x566.jpg","width":800,"height":566,"filesize":96936,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-800x566.jpg"},"size_242":{"file":"program-nou-evenimente-242x171.jpg","width":242,"height":171,"filesize":11777,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-242x171.jpg"},"size_242_198":{"file":"program-nou-evenimente-242x198.jpg","width":242,"height":198,"filesize":14234,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-242x198.jpg"},"size_254_198":{"file":"program-nou-evenimente-254x198.jpg","width":254,"height":198,"filesize":14776,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-254x198.jpg"},"size_140_90":{"file":"program-nou-evenimente-140x90.jpg","width":140,"height":90,"filesize":4823,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-140x90.jpg"},"size_90":{"file":"program-nou-evenimente-90x64.jpg","width":90,"height":64,"filesize":2610,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-90x64.jpg"},"size_90_90":{"file":"program-nou-evenimente-90x90.jpg","width":90,"height":90,"filesize":3384,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-90x90.jpg"},"woocommerce_thumbnail":{"file":"program-nou-evenimente-174x245.jpg","width":174,"height":245,"filesize":12593,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-174x245.jpg"},"woocommerce_single":{"file":"program-nou-evenimente-290x205.jpg","width":290,"height":205,"filesize":15928,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-290x205.jpg"},"woocommerce_gallery_thumbnail":{"file":"program-nou-evenimente-100x100.jpg","width":100,"height":100,"filesize":3975,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente-100x100.jpg"},"full":{"file":"program-nou-evenimente.jpg","width":2327,"height":1646,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/05\/program-nou-evenimente.jpg","_links":{"self":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/media\/38576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/users\/2010"}],"replies":[{"embeddable":true,"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/comments?post=38576"}]}}