{"id":38763,"date":"2023-06-08T12:08:08","date_gmt":"2023-06-08T09:08:08","guid":{"rendered":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover.jpg"},"modified":"2023-06-08T12:08:08","modified_gmt":"2023-06-08T09:08:08","slug":"idee-si-vesmant1_frontcover","status":"inherit","type":"attachment","link":"https:\/\/editura-unibuc.ro\/en\/idee-si-vesmant1_frontcover\/","title":{"rendered":"Idee-si-Vesmant1_frontcover"},"author":2010,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-38763","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-scaled.jpg' rel=\"lightbox[38763]\"><img loading=\"lazy\" decoding=\"async\" width=\"270\" height=\"400\" src=\"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-270x400.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1726,"height":2560,"file":"2023\/06\/Idee-si-Vesmant1_frontcover-scaled.jpg","filesize":241053,"sizes":{"medium":{"file":"Idee-si-Vesmant1_frontcover-270x400.jpg","width":270,"height":400,"filesize":16917,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-270x400.jpg"},"large":{"file":"Idee-si-Vesmant1_frontcover-540x800.jpg","width":540,"height":800,"filesize":44815,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-540x800.jpg"},"thumbnail":{"file":"Idee-si-Vesmant1_frontcover-101x150.jpg","width":101,"height":150,"filesize":4561,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-101x150.jpg"},"medium_large":{"file":"Idee-si-Vesmant1_frontcover-768x1139.jpg","width":768,"height":1139,"filesize":74606,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-768x1139.jpg"},"1536x1536":{"file":"Idee-si-Vesmant1_frontcover-1036x1536.jpg","width":1036,"height":1536,"filesize":113006,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-1036x1536.jpg"},"2048x2048":{"file":"Idee-si-Vesmant1_frontcover-1381x2048.jpg","width":1381,"height":2048,"filesize":173491,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-1381x2048.jpg"},"post-thumbnail":{"file":"Idee-si-Vesmant1_frontcover-800x1186.jpg","width":800,"height":1186,"filesize":78489,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-800x1186.jpg"},"size_242":{"file":"Idee-si-Vesmant1_frontcover-242x359.jpg","width":242,"height":359,"filesize":14821,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-242x359.jpg"},"size_242_198":{"file":"Idee-si-Vesmant1_frontcover-242x198.jpg","width":242,"height":198,"filesize":11165,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-242x198.jpg"},"size_254_198":{"file":"Idee-si-Vesmant1_frontcover-254x198.jpg","width":254,"height":198,"filesize":11428,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-254x198.jpg"},"size_140_90":{"file":"Idee-si-Vesmant1_frontcover-140x90.jpg","width":140,"height":90,"filesize":4416,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-140x90.jpg"},"size_90":{"file":"Idee-si-Vesmant1_frontcover-90x133.jpg","width":90,"height":133,"filesize":3836,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-90x133.jpg"},"size_90_90":{"file":"Idee-si-Vesmant1_frontcover-90x90.jpg","width":90,"height":90,"filesize":3390,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-90x90.jpg"},"woocommerce_thumbnail":{"file":"Idee-si-Vesmant1_frontcover-174x245.jpg","width":174,"height":245,"filesize":9363,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-174x245.jpg"},"woocommerce_single":{"file":"Idee-si-Vesmant1_frontcover-290x430.jpg","width":290,"height":430,"filesize":18994,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-290x430.jpg"},"woocommerce_gallery_thumbnail":{"file":"Idee-si-Vesmant1_frontcover-100x100.jpg","width":100,"height":100,"filesize":3829,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-100x100.jpg"},"full":{"file":"Idee-si-Vesmant1_frontcover-scaled.jpg","width":1726,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Idee-si-Vesmant1_frontcover.jpg"},"post":null,"source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/Idee-si-Vesmant1_frontcover-scaled.jpg","_links":{"self":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/media\/38763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/users\/2010"}],"replies":[{"embeddable":true,"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/comments?post=38763"}]}}