{"id":38931,"date":"2023-06-20T13:09:39","date_gmt":"2023-06-20T10:09:39","guid":{"rendered":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2.jpg"},"modified":"2023-06-20T13:09:39","modified_gmt":"2023-06-20T10:09:39","slug":"banner-bookfest-end2","status":"inherit","type":"attachment","link":"https:\/\/editura-unibuc.ro\/en\/banner-bookfest-end2\/","title":{"rendered":"banner bookfest end2"},"author":2010,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-38931","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2.jpg' rel=\"lightbox[38931]\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"282\" src=\"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-400x282.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":564,"file":"2023\/06\/banner-bookfest-end2.jpg","filesize":402805,"sizes":{"medium":{"file":"banner-bookfest-end2-400x282.jpg","width":400,"height":282,"filesize":35285,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-400x282.jpg"},"thumbnail":{"file":"banner-bookfest-end2-150x106.jpg","width":150,"height":106,"filesize":7540,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-150x106.jpg"},"medium_large":{"file":"banner-bookfest-end2-768x541.jpg","width":768,"height":541,"filesize":91806,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-768x541.jpg"},"size_242":{"file":"banner-bookfest-end2-242x171.jpg","width":242,"height":171,"filesize":15874,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-242x171.jpg"},"size_242_198":{"file":"banner-bookfest-end2-242x198.jpg","width":242,"height":198,"filesize":17262,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-242x198.jpg"},"size_254_198":{"file":"banner-bookfest-end2-254x198.jpg","width":254,"height":198,"filesize":18062,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-254x198.jpg"},"size_140_90":{"file":"banner-bookfest-end2-140x90.jpg","width":140,"height":90,"filesize":6229,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-140x90.jpg"},"size_90":{"file":"banner-bookfest-end2-90x63.jpg","width":90,"height":63,"filesize":3416,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-90x63.jpg"},"size_90_90":{"file":"banner-bookfest-end2-90x90.jpg","width":90,"height":90,"filesize":4385,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-90x90.jpg"},"woocommerce_thumbnail":{"file":"banner-bookfest-end2-174x245.jpg","width":174,"height":245,"filesize":13748,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-174x245.jpg"},"woocommerce_single":{"file":"banner-bookfest-end2-290x204.jpg","width":290,"height":204,"filesize":20899,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-290x204.jpg"},"woocommerce_gallery_thumbnail":{"file":"banner-bookfest-end2-100x100.jpg","width":100,"height":100,"filesize":5063,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2-100x100.jpg"},"full":{"file":"banner-bookfest-end2.jpg","width":800,"height":564,"mime_type":"image\/jpeg","source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/editura-unibuc.ro\/wp-content\/uploads\/2023\/06\/banner-bookfest-end2.jpg","_links":{"self":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/media\/38931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/users\/2010"}],"replies":[{"embeddable":true,"href":"https:\/\/editura-unibuc.ro\/en\/wp-json\/wp\/v2\/comments?post=38931"}]}}